{"id":53501,"date":"2026-05-13T13:58:59","date_gmt":"2026-05-13T16:58:59","guid":{"rendered":"https:\/\/consejomagistratura.gov.ar\/?p=53501"},"modified":"2026-05-13T13:59:00","modified_gmt":"2026-05-13T16:59:00","slug":"sesionaron-las-comisiones-de-seleccion-y-de-disciplina","status":"publish","type":"post","link":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/","title":{"rendered":"Sesionaron las Comisiones de Selecci\u00f3n y de Disciplina"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-1024x682.jpg\" alt=\"\" class=\"wp-image-53517\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>El Consejo de la Magistratura de la Naci\u00f3n celebr\u00f3 este mi\u00e9rcoles 13 de mayo una importante jornada de reuniones en dos de sus comisiones.<\/p>\n\n\n\n<p><strong>Comisi\u00f3n de Selecci\u00f3n y Escuela Judicial<\/strong><\/p>\n\n\n\n<p>La Comisi\u00f3n de Selecci\u00f3n abri\u00f3 la actividad y dio impulso a varios concursos judiciales. Presidi\u00f3 el encuentro su titular, Mar\u00eda Fernanda Vazquez, con la asistencia de la Secretaria Ingrid Jorgensen. Participaron los\/as Consejeros\/as Diego Barroetave\u00f1a, Agustina D\u00edaz Cordero, Hugo Galderisi, C\u00e9sar Grau, Luis Juez, Alberto Lugones, Alberto Maques, Alejandra Prov\u00edtola, Gonzalo Roca, Vanesa Siley, Santiago Viola y Eduardo Vischi.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53510\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2834-1024x682.jpg\" alt=\"\" class=\"wp-image-53510\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2834-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2834-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2834-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2834-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2834-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53512\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2814-1024x682.jpg\" alt=\"\" class=\"wp-image-53512\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2814-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2814-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2814-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2814-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2814-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>La sesi\u00f3n se inici\u00f3 con la aprobaci\u00f3n del acta de la reuni\u00f3n anterior, seguida del informe de la Presidencia y el de la Secretar\u00eda. La Presidenta destac\u00f3 el trabajo mancomunado entre los integrantes de la Comisi\u00f3n, valor\u00f3 la construcci\u00f3n de consensos y la riqueza del intercambio institucional, y anunci\u00f3 las actividades previstas para las pr\u00f3ximas semanas en el marco de diversos concursos en tr\u00e1mite.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53514\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2800-1024x682.jpg\" alt=\"\" class=\"wp-image-53514\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2800-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2800-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2800-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2800-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2800-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53513\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2811-1024x682.jpg\" alt=\"\" class=\"wp-image-53513\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2811-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2811-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2811-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2811-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2811-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>A continuaci\u00f3n, se analizaron los informes con el an\u00e1lisis de las impugnaciones en dos concursos, destinados a cubrir vacantes en la provincia de Santa Fe. Se trata de los Concursos: 496 \u2013C\u00e1mara Federal de Apelaciones de Rosario\u2013 y 521 \u2013Juzgado Federal de Primera Instancia N\u00b0 1 de Santa Fe\u2013. Aprobados los informes, la Comisi\u00f3n resolvi\u00f3 convocar a entrevistas personales a una lista de candidatos en cada Concurso.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53511\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2822-1024x682.jpg\" alt=\"\" class=\"wp-image-53511\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2822-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2822-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2822-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2822-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2822-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53516\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2791-1024x682.jpg\" alt=\"\" class=\"wp-image-53516\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2791-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2791-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2791-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2791-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2791-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>La sesi\u00f3n culmin\u00f3 con el sorteo de la subcomisi\u00f3n que tendr\u00e1 a su cargo el an\u00e1lisis de las impugnaciones en el Concurso 528, correspondiente al Juzgado Federal de Primera Instancia N\u00b0 4 de Rosario, provincia de Santa Fe.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_3013-1024x682.jpg\" alt=\"\" class=\"wp-image-53503\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_3013-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_3013-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_3013-768x512.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_3013-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_3013-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Comisi\u00f3n de Disciplina<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53504\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2983-1024x682.jpg\" alt=\"\" class=\"wp-image-53504\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2983-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2983-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2983-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2983-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2983-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Al finalizar la Comisi\u00f3n de Selecci\u00f3n, se llev\u00f3 a cabo la sesi\u00f3n extraordinaria de la Comisi\u00f3n de Disciplina. El encuentro fue presidido por su titular, C\u00e9sar Grau, con la asistencia de la secretaria Laura Gonz\u00e1lez. Participaron los\/as Consejeros\/as Diego Barroetave\u00f1a, Agustina D\u00edaz Cordero, Anabel Fern\u00e1ndez Sagasti, Hugo Galderisi, Luis Juez, Alberto Lugones, Alejandra Prov\u00edtola, Mariano Recalde, Vanesa Siley y Eduardo Vischi.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53507\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2893-1024x682.jpg\" alt=\"\" class=\"wp-image-53507\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2893-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2893-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2893-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2893-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2893-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53508\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2870-1024x682.jpg\" alt=\"\" class=\"wp-image-53508\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2870-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2870-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2870-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2870-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2870-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>La reuni\u00f3n tuvo su eje central en la causa seguida contra el juez Hern\u00e1n Diego Papa, magistrado a cargo del Juzgado Nacional de Primera Instancia en lo Comercial N\u00b0 12. La denuncia que dio origen al expediente hab\u00eda sido formulada por Julio Piumato, Roc\u00edo Herrera y Juan \u00c1lvarez, representantes de la Uni\u00f3n de Empleados de la Justicia de la Naci\u00f3n (UEJN).<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53506\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2913-1024x682.jpg\" alt=\"\" class=\"wp-image-53506\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2913-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2913-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2913-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2913-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2913-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53509\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2846-1024x682.jpg\" alt=\"\" class=\"wp-image-53509\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2846-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2846-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2846-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2846-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2846-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Luego de un intercambio de opiniones y escuchadas las posiciones de los\/as Consejeros\/as, la Comisi\u00f3n aprob\u00f3 por mayor\u00eda el proyecto que propone al Plenario aplicar al magistrado la sanci\u00f3n de multa del treinta por ciento (30%) de sus haberes, por considerar que su conducta encuadra en las faltas disciplinarias previstas en la Ley 24.937 y modificatorias. El dictamen emitido en Comisi\u00f3n -con las propuestas de mayor\u00eda y minor\u00eda- ser\u00e1 elevado a consideraci\u00f3n del Pleno del Consejo de la Magistratura.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53515\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2796-1024x682.jpg\" alt=\"\" class=\"wp-image-53515\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2796-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2796-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2796-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2796-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2796-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"53505\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2964-1024x682.jpg\" alt=\"\" class=\"wp-image-53505\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2964-1024x682.jpg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2964-300x200.jpg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2964-768x511.jpg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2964-1536x1023.jpg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2964-2048x1364.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>A continuaci\u00f3n de las sesiones, la Comisi\u00f3n de Selecci\u00f3n realiz\u00f3 en la misma Sala el acto de develaci\u00f3n de claves de concursos en tr\u00e1mite en los que se hab\u00eda recibido con anterioridad la prueba de oposici\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-13.22.26-1024x682.jpeg\" alt=\"\" class=\"wp-image-53502\" srcset=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-13.22.26-1024x682.jpeg 1024w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-13.22.26-300x200.jpeg 300w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-13.22.26-768x511.jpeg 768w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-13.22.26-1536x1022.jpeg 1536w, https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-13.22.26-2048x1363.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Los encuentros se realizaron en modalidad semipresencial en la Sala de Plenario \u201cLino E. Palacio\u201d, ubicada en Libertad 731, piso 2\u00b0, de la Ciudad Aut\u00f3noma de Buenos Aires, con transmisi\u00f3n en vivo a trav\u00e9s de este portal y el Canal en YouTube del Organismo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Reuniones de la Comisi\u00f3n de Selecci\u00f3n y de la Comisi\u00f3n de Disciplina 13\/05\/2026\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/vDwdKOsOdVs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo de la Magistratura de la Naci\u00f3n celebr\u00f3 este mi\u00e9rcoles 13 de mayo una importante jornada de reuniones en dos de sus comisiones. Comisi\u00f3n de Selecci\u00f3n y Escuela Judicial La Comisi\u00f3n de Selecci\u00f3n abri\u00f3 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":53517,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130,18,4,79],"tags":[],"class_list":["post-53501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comision-de-disciplina","category-seleccion","category-comisiones","category-transmisiones-en-vivo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v16.2 (Yoast SEO v17.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sesionaron las Comisiones de Selecci\u00f3n y de Disciplina | Consejo de la Magistratura<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sesionaron las Comisiones de Selecci\u00f3n y de Disciplina | Consejo de la Magistratura\" \/>\n<meta property=\"og:description\" content=\"El Consejo de la Magistratura de la Naci\u00f3n celebr\u00f3 este mi\u00e9rcoles 13 de mayo una importante jornada de reuniones en dos de sus comisiones. Comisi\u00f3n de Selecci\u00f3n y Escuela Judicial La Comisi\u00f3n de Selecci\u00f3n abri\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/\" \/>\n<meta property=\"og:site_name\" content=\"Consejo de la Magistratura\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/consejomagistratura\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T16:58:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T16:59:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cmagistratura\" \/>\n<meta name=\"twitter:site\" content=\"@cmagistratura\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"hernanelman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/consejomagistratura.gov.ar\/#organization\",\"name\":\"Consejo de la Magistratura\",\"url\":\"https:\/\/consejomagistratura.gov.ar\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/consejomagistratura\",\"https:\/\/www.instagram.com\/consejodelamagistratura\/\",\"https:\/\/www.youtube.com\/c\/consejodelamagistraturadelanacion\",\"https:\/\/es.wikipedia.org\/wiki\/Consejo_de_la_Magistratura_(Argentina)\",\"https:\/\/twitter.com\/cmagistratura\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/consejomagistratura.gov.ar\/#logo\",\"inLanguage\":\"es-AR\",\"url\":\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2021\/08\/logo_link_2_Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2021\/08\/logo_link_2_Mesa-de-trabajo-1.png\",\"width\":1067,\"height\":780,\"caption\":\"Consejo de la Magistratura\"},\"image\":{\"@id\":\"https:\/\/consejomagistratura.gov.ar\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/consejomagistratura.gov.ar\/#website\",\"url\":\"https:\/\/consejomagistratura.gov.ar\/\",\"name\":\"Consejo de la Magistratura\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/consejomagistratura.gov.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/consejomagistratura.gov.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-AR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#primaryimage\",\"inLanguage\":\"es-AR\",\"url\":\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-scaled.jpg\",\"contentUrl\":\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-scaled.jpg\",\"width\":2560,\"height\":1705},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#webpage\",\"url\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/\",\"name\":\"Sesionaron las Comisiones de Selecci\\u00f3n y de Disciplina | Consejo de la Magistratura\",\"isPartOf\":{\"@id\":\"https:\/\/consejomagistratura.gov.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#primaryimage\"},\"datePublished\":\"2026-05-13T16:58:59+00:00\",\"dateModified\":\"2026-05-13T16:59:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/consejomagistratura.gov.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sesionaron las Comisiones de Selecci\\u00f3n y de Disciplina\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#webpage\"},\"author\":{\"@id\":\"https:\/\/consejomagistratura.gov.ar\/#\/schema\/person\/4da57063f408a85d886d958badf8f6df\"},\"headline\":\"Sesionaron las Comisiones de Selecci\\u00f3n y de Disciplina\",\"datePublished\":\"2026-05-13T16:58:59+00:00\",\"dateModified\":\"2026-05-13T16:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#webpage\"},\"wordCount\":612,\"publisher\":{\"@id\":\"https:\/\/consejomagistratura.gov.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-scaled.jpg\",\"articleSection\":[\"Comisi\\u00f3n de Disciplina\",\"Comisi\\u00f3n de Selecci\\u00f3n de Magistrados y Escuela Judicial\",\"Comisiones\",\"Transmisiones en Vivo\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/consejomagistratura.gov.ar\/#\/schema\/person\/4da57063f408a85d886d958badf8f6df\",\"name\":\"hernanelman\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/consejomagistratura.gov.ar\/#personlogo\",\"inLanguage\":\"es-AR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb37cc646e6a84fe6e78061c6d9d5fb02a35404aaf0d46840fd3257e6c0131f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb37cc646e6a84fe6e78061c6d9d5fb02a35404aaf0d46840fd3257e6c0131f2?s=96&d=mm&r=g\",\"caption\":\"hernanelman\"},\"url\":\"https:\/\/consejomagistratura.gov.ar\/index.php\/author\/hernanelman\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sesionaron las Comisiones de Selecci\u00f3n y de Disciplina | Consejo de la Magistratura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/","og_locale":"es_ES","og_type":"article","og_title":"Sesionaron las Comisiones de Selecci\u00f3n y de Disciplina | Consejo de la Magistratura","og_description":"El Consejo de la Magistratura de la Naci\u00f3n celebr\u00f3 este mi\u00e9rcoles 13 de mayo una importante jornada de reuniones en dos de sus comisiones. Comisi\u00f3n de Selecci\u00f3n y Escuela Judicial La Comisi\u00f3n de Selecci\u00f3n abri\u00f3 [&hellip;]","og_url":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/","og_site_name":"Consejo de la Magistratura","article_publisher":"https:\/\/www.facebook.com\/consejomagistratura","article_published_time":"2026-05-13T16:58:59+00:00","article_modified_time":"2026-05-13T16:59:00+00:00","og_image":[{"width":2560,"height":1705,"url":"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@cmagistratura","twitter_site":"@cmagistratura","twitter_misc":{"Escrito por":"hernanelman","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/consejomagistratura.gov.ar\/#organization","name":"Consejo de la Magistratura","url":"https:\/\/consejomagistratura.gov.ar\/","sameAs":["https:\/\/www.facebook.com\/consejomagistratura","https:\/\/www.instagram.com\/consejodelamagistratura\/","https:\/\/www.youtube.com\/c\/consejodelamagistraturadelanacion","https:\/\/es.wikipedia.org\/wiki\/Consejo_de_la_Magistratura_(Argentina)","https:\/\/twitter.com\/cmagistratura"],"logo":{"@type":"ImageObject","@id":"https:\/\/consejomagistratura.gov.ar\/#logo","inLanguage":"es-AR","url":"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2021\/08\/logo_link_2_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2021\/08\/logo_link_2_Mesa-de-trabajo-1.png","width":1067,"height":780,"caption":"Consejo de la Magistratura"},"image":{"@id":"https:\/\/consejomagistratura.gov.ar\/#logo"}},{"@type":"WebSite","@id":"https:\/\/consejomagistratura.gov.ar\/#website","url":"https:\/\/consejomagistratura.gov.ar\/","name":"Consejo de la Magistratura","description":"","publisher":{"@id":"https:\/\/consejomagistratura.gov.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/consejomagistratura.gov.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-AR"},{"@type":"ImageObject","@id":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#primaryimage","inLanguage":"es-AR","url":"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-scaled.jpg","contentUrl":"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-scaled.jpg","width":2560,"height":1705},{"@type":"WebPage","@id":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#webpage","url":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/","name":"Sesionaron las Comisiones de Selecci\u00f3n y de Disciplina | Consejo de la Magistratura","isPartOf":{"@id":"https:\/\/consejomagistratura.gov.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#primaryimage"},"datePublished":"2026-05-13T16:58:59+00:00","dateModified":"2026-05-13T16:59:00+00:00","breadcrumb":{"@id":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/consejomagistratura.gov.ar\/"},{"@type":"ListItem","position":2,"name":"Sesionaron las Comisiones de Selecci\u00f3n y de Disciplina"}]},{"@type":"Article","@id":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#article","isPartOf":{"@id":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#webpage"},"author":{"@id":"https:\/\/consejomagistratura.gov.ar\/#\/schema\/person\/4da57063f408a85d886d958badf8f6df"},"headline":"Sesionaron las Comisiones de Selecci\u00f3n y de Disciplina","datePublished":"2026-05-13T16:58:59+00:00","dateModified":"2026-05-13T16:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#webpage"},"wordCount":612,"publisher":{"@id":"https:\/\/consejomagistratura.gov.ar\/#organization"},"image":{"@id":"https:\/\/consejomagistratura.gov.ar\/index.php\/2026\/05\/13\/sesionaron-las-comisiones-de-seleccion-y-de-disciplina\/#primaryimage"},"thumbnailUrl":"https:\/\/consejomagistratura.gov.ar\/wp-content\/uploads\/2026\/05\/DSC_2778-1-scaled.jpg","articleSection":["Comisi\u00f3n de Disciplina","Comisi\u00f3n de Selecci\u00f3n de Magistrados y Escuela Judicial","Comisiones","Transmisiones en Vivo"],"inLanguage":"es-AR"},{"@type":"Person","@id":"https:\/\/consejomagistratura.gov.ar\/#\/schema\/person\/4da57063f408a85d886d958badf8f6df","name":"hernanelman","image":{"@type":"ImageObject","@id":"https:\/\/consejomagistratura.gov.ar\/#personlogo","inLanguage":"es-AR","url":"https:\/\/secure.gravatar.com\/avatar\/cb37cc646e6a84fe6e78061c6d9d5fb02a35404aaf0d46840fd3257e6c0131f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb37cc646e6a84fe6e78061c6d9d5fb02a35404aaf0d46840fd3257e6c0131f2?s=96&d=mm&r=g","caption":"hernanelman"},"url":"https:\/\/consejomagistratura.gov.ar\/index.php\/author\/hernanelman\/"}]}},"_links":{"self":[{"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/posts\/53501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/comments?post=53501"}],"version-history":[{"count":1,"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/posts\/53501\/revisions"}],"predecessor-version":[{"id":53518,"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/posts\/53501\/revisions\/53518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/media\/53517"}],"wp:attachment":[{"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/media?parent=53501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/categories?post=53501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consejomagistratura.gov.ar\/index.php\/wp-json\/wp\/v2\/tags?post=53501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}